{"id":3930,"date":"2016-09-19T16:51:42","date_gmt":"2016-09-19T21:51:42","guid":{"rendered":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946.jpg"},"modified":"2016-09-19T16:54:18","modified_gmt":"2016-09-19T21:54:18","slug":"img_1946","status":"inherit","type":"attachment","link":"https:\/\/www.senasa.gob.pe\/senasacontigo\/ayacucho-fiscalizacion-en-establecimientos-que-expenden-insumos-agropecuarios\/img_1946\/","title":{"rendered":"Fiscalizaci\u00f3n a agroveterinarias en el distrito de Puquio"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"tdm_status":"","tdm_grid_status":""},"class_list":["post-3930","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscalizaci\u00f3n a agroveterinarias en el distrito de Puquio - SENASA al d\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946.jpg\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscalizaci\u00f3n a agroveterinarias en el distrito de Puquio - SENASA al d\u00eda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946.jpg\" \/>\n<meta property=\"og:site_name\" content=\"SENASA al d\u00eda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/senasape\/?fref=ts\" \/>\n<meta property=\"article:modified_time\" content=\"2016-09-19T21:54:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-1024x768.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946.jpg\",\"url\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946.jpg\",\"name\":\"Fiscalizaci\u00f3n a agroveterinarias en el distrito de Puquio - SENASA al d\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/#website\"},\"datePublished\":\"2016-09-19T21:51:42+00:00\",\"dateModified\":\"2016-09-19T21:54:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946.jpg#breadcrumb\"},\"inLanguage\":\"es-PE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ayacucho: fiscalizaci\u00f3n en establecimientos que expenden insumos agropecuarios\",\"item\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/ayacucho-fiscalizacion-en-establecimientos-que-expenden-insumos-agropecuarios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fiscalizaci\u00f3n a agroveterinarias en el distrito de Puquio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/#website\",\"url\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/\",\"name\":\"SENASA al d\u00eda\",\"description\":\"Blog de SENASA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-PE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscalizaci\u00f3n a agroveterinarias en el distrito de Puquio - SENASA al d\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946.jpg","og_locale":"es_ES","og_type":"article","og_title":"Fiscalizaci\u00f3n a agroveterinarias en el distrito de Puquio - SENASA al d\u00eda","og_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946.jpg","og_site_name":"SENASA al d\u00eda","article_publisher":"https:\/\/www.facebook.com\/senasape\/?fref=ts","article_modified_time":"2016-09-19T21:54:18+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-1024x768.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946.jpg","url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946.jpg","name":"Fiscalizaci\u00f3n a agroveterinarias en el distrito de Puquio - SENASA al d\u00eda","isPartOf":{"@id":"https:\/\/www.senasa.gob.pe\/senasacontigo\/#website"},"datePublished":"2016-09-19T21:51:42+00:00","dateModified":"2016-09-19T21:54:18+00:00","breadcrumb":{"@id":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946.jpg#breadcrumb"},"inLanguage":"es-PE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.senasa.gob.pe\/senasacontigo\/"},{"@type":"ListItem","position":2,"name":"Ayacucho: fiscalizaci\u00f3n en establecimientos que expenden insumos agropecuarios","item":"https:\/\/www.senasa.gob.pe\/senasacontigo\/ayacucho-fiscalizacion-en-establecimientos-que-expenden-insumos-agropecuarios\/"},{"@type":"ListItem","position":3,"name":"Fiscalizaci\u00f3n a agroveterinarias en el distrito de Puquio"}]},{"@type":"WebSite","@id":"https:\/\/www.senasa.gob.pe\/senasacontigo\/#website","url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/","name":"SENASA al d\u00eda","description":"Blog de SENASA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.senasa.gob.pe\/senasacontigo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-PE"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-300x225.jpg 300w, https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-768x576.jpg 768w, https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-1024x768.jpg 1024w, https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-80x60.jpg 80w, https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-265x198.jpg 265w, https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-696x522.jpg 696w, https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-1068x801.jpg 1068w, https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-560x420.jpg 560w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":4608,"height":3456,"file":"2016\/09\/IMG_1946.jpg","sizes":{"thumbnail":{"file":"IMG_1946-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-150x150.jpg"},"medium":{"file":"IMG_1946-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-300x225.jpg"},"medium_large":{"file":"IMG_1946-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-768x576.jpg"},"large":{"file":"IMG_1946-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-1024x768.jpg"},"td_80x60":{"file":"IMG_1946-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-80x60.jpg"},"td_100x70":{"file":"IMG_1946-100x70.jpg","width":100,"height":70,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-100x70.jpg"},"td_218x150":{"file":"IMG_1946-218x150.jpg","width":218,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-218x150.jpg"},"td_265x198":{"file":"IMG_1946-265x198.jpg","width":265,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-265x198.jpg"},"td_324x160":{"file":"IMG_1946-324x160.jpg","width":324,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-324x160.jpg"},"td_324x235":{"file":"IMG_1946-324x235.jpg","width":324,"height":235,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-324x235.jpg"},"td_324x400":{"file":"IMG_1946-324x400.jpg","width":324,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-324x400.jpg"},"td_356x220":{"file":"IMG_1946-356x220.jpg","width":356,"height":220,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-356x220.jpg"},"td_356x364":{"file":"IMG_1946-356x364.jpg","width":356,"height":364,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-356x364.jpg"},"td_533x261":{"file":"IMG_1946-533x261.jpg","width":533,"height":261,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-533x261.jpg"},"td_534x462":{"file":"IMG_1946-534x462.jpg","width":534,"height":462,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-534x462.jpg"},"td_696x0":{"file":"IMG_1946-696x522.jpg","width":696,"height":522,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-696x522.jpg"},"td_696x385":{"file":"IMG_1946-696x385.jpg","width":696,"height":385,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-696x385.jpg"},"td_741x486":{"file":"IMG_1946-741x486.jpg","width":741,"height":486,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-741x486.jpg"},"td_1068x580":{"file":"IMG_1946-1068x580.jpg","width":1068,"height":580,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-1068x580.jpg"},"td_1068x0":{"file":"IMG_1946-1068x801.jpg","width":1068,"height":801,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-1068x801.jpg"},"td_0x420":{"file":"IMG_1946-560x420.jpg","width":560,"height":420,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946-560x420.jpg"},"full":{"file":"IMG_1946.jpg","width":4608,"height":3456,"mime_type":"image\/jpeg","source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946.jpg"}},"image_meta":{"aperture":"3.5","credit":"","camera":"Canon PowerShot SX170 IS","caption":"","created_timestamp":"1473872936","copyright":"","focal_length":"5","iso":"800","shutter_speed":"0.076923076923077","title":"","orientation":"1","keywords":[]}},"post":3927,"source_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-content\/uploads\/2016\/09\/IMG_1946.jpg","_links":{"self":[{"href":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-json\/wp\/v2\/media\/3930"}],"collection":[{"href":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-json\/wp\/v2\/comments?post=3930"}]}}