{"id":1667,"count":1,"description":"","link":"https:\/\/www.senasa.gob.pe\/senasacontigo\/tag\/chavin\/","name":"Chav\u00edn","slug":"chavin","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chav\u00edn Archives - SENASA al d\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.senasa.gob.pe\/senasacontigo\/tag\/chavin\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chav\u00edn Archives - SENASA al d\u00eda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.senasa.gob.pe\/senasacontigo\/tag\/chavin\/\" \/>\n<meta property=\"og:site_name\" content=\"SENASA al d\u00eda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/tag\/chavin\/\",\"url\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/tag\/chavin\/\",\"name\":\"Chav\u00edn Archives - SENASA al d\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/tag\/chavin\/#breadcrumb\"},\"inLanguage\":\"es-PE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/tag\/chavin\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chav\u00edn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/#website\",\"url\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/\",\"name\":\"SENASA al d\u00eda\",\"description\":\"Blog de SENASA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.senasa.gob.pe\/senasacontigo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-PE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chav\u00edn Archives - SENASA al d\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.senasa.gob.pe\/senasacontigo\/tag\/chavin\/","og_locale":"es_ES","og_type":"article","og_title":"Chav\u00edn Archives - SENASA al d\u00eda","og_url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/tag\/chavin\/","og_site_name":"SENASA al d\u00eda","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.senasa.gob.pe\/senasacontigo\/tag\/chavin\/","url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/tag\/chavin\/","name":"Chav\u00edn Archives - SENASA al d\u00eda","isPartOf":{"@id":"https:\/\/www.senasa.gob.pe\/senasacontigo\/#website"},"breadcrumb":{"@id":"https:\/\/www.senasa.gob.pe\/senasacontigo\/tag\/chavin\/#breadcrumb"},"inLanguage":"es-PE"},{"@type":"BreadcrumbList","@id":"https:\/\/www.senasa.gob.pe\/senasacontigo\/tag\/chavin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.senasa.gob.pe\/senasacontigo\/"},{"@type":"ListItem","position":2,"name":"Chav\u00edn"}]},{"@type":"WebSite","@id":"https:\/\/www.senasa.gob.pe\/senasacontigo\/#website","url":"https:\/\/www.senasa.gob.pe\/senasacontigo\/","name":"SENASA al d\u00eda","description":"Blog de SENASA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.senasa.gob.pe\/senasacontigo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-PE"}]}},"_links":{"self":[{"href":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-json\/wp\/v2\/tags\/1667"}],"collection":[{"href":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.senasa.gob.pe\/senasacontigo\/wp-json\/wp\/v2\/posts?tags=1667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}